{"id":27585,"date":"2019-02-19T22:34:44","date_gmt":"2019-02-19T22:34:44","guid":{"rendered":"https:\/\/midwesttradingus.com\/en\/?product=now-later-extreme-sour-24ct-bars"},"modified":"2023-10-06T22:31:54","modified_gmt":"2023-10-06T22:31:54","slug":"now-later-extreme-sour-24ct-bars","status":"publish","type":"product","link":"https:\/\/midwesttradingus.com\/en\/product\/now-later-extreme-sour-24ct-bars\/","title":{"rendered":"NOW &#038; LATER EXTREME SOUR 24CT. BARS"},"content":{"rendered":"<p>NOW &#038; LATER EXTREME SOUR 24CT. BARS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOW &#038; LATER EXTREME SOUR 24CT. BARS<\/p>\n","protected":false},"featured_media":27586,"template":"","meta":[],"product_brand":[],"product_cat":[819],"product_tag":[],"class_list":{"0":"post-27585","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-candy","8":"first","9":"onbackorder","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product\/27585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product\/27585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/media\/27586"}],"wp:attachment":[{"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/media?parent=27585"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product_brand?post=27585"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product_cat?post=27585"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/midwesttradingus.com\/en\/wp-json\/wp\/v2\/product_tag?post=27585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}